{"id":1910,"count":11,"description":"Accessories for Taekwondo WT. Keychains, water bottles, equipment bags, bandage adhesive tapes. To make Taekwondo training better.","link":"https:\/\/prideshop.eu\/en\/product-category\/sports\/taekwondo-wt-olympic-sports\/taekwondo-wt-accessories\/","name":"Taekwondo WT Accessories","slug":"taekwondo-wt-accessories","taxonomy":"product_cat","parent":755,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taekwondo WT Accessories - PRIDEshop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prideshop.eu\/en\/product-category\/sports\/taekwondo-wt-olympic-sports\/taekwondo-wt-accessories\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taekwondo WT Accessories - PRIDEshop\" \/>\n<meta property=\"og:description\" content=\"Accessories for Taekwondo WT. Keychains, water bottles, equipment bags, bandage adhesive tapes. To make Taekwondo training better.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prideshop.eu\/en\/product-category\/sports\/taekwondo-wt-olympic-sports\/taekwondo-wt-accessories\/\" \/>\n<meta property=\"og:site_name\" content=\"PRIDEshop\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/product-category\\\/sports\\\/taekwondo-wt-olympic-sports\\\/taekwondo-wt-accessories\\\/\",\"url\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/product-category\\\/sports\\\/taekwondo-wt-olympic-sports\\\/taekwondo-wt-accessories\\\/\",\"name\":\"Taekwondo WT Accessories - PRIDEshop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/product-category\\\/sports\\\/taekwondo-wt-olympic-sports\\\/taekwondo-wt-accessories\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/product-category\\\/sports\\\/taekwondo-wt-olympic-sports\\\/taekwondo-wt-accessories\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sports\",\"item\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/product-category\\\/sports\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Taekwondo WT Olympic sports\",\"item\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/product-category\\\/sports\\\/taekwondo-wt-olympic-sports\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Taekwondo WT Accessories\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/\",\"name\":\"PRIDEshop\",\"description\":\"Oprema za Borilne \u0160porte\",\"publisher\":{\"@id\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/#organization\",\"name\":\"PRIDEshop\",\"url\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"PRIDEshop\"},\"image\":{\"@id\":\"https:\\\/\\\/prideshop.eu\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/sl-si.facebook.com\\\/PrideShopeu\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taekwondo WT Accessories - PRIDEshop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prideshop.eu\/en\/product-category\/sports\/taekwondo-wt-olympic-sports\/taekwondo-wt-accessories\/","og_locale":"en_US","og_type":"article","og_title":"Taekwondo WT Accessories - PRIDEshop","og_description":"Accessories for Taekwondo WT. Keychains, water bottles, equipment bags, bandage adhesive tapes. To make Taekwondo training better.","og_url":"https:\/\/prideshop.eu\/en\/product-category\/sports\/taekwondo-wt-olympic-sports\/taekwondo-wt-accessories\/","og_site_name":"PRIDEshop","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/prideshop.eu\/en\/product-category\/sports\/taekwondo-wt-olympic-sports\/taekwondo-wt-accessories\/","url":"https:\/\/prideshop.eu\/en\/product-category\/sports\/taekwondo-wt-olympic-sports\/taekwondo-wt-accessories\/","name":"Taekwondo WT Accessories - PRIDEshop","isPartOf":{"@id":"https:\/\/prideshop.eu\/en\/#website"},"breadcrumb":{"@id":"https:\/\/prideshop.eu\/en\/product-category\/sports\/taekwondo-wt-olympic-sports\/taekwondo-wt-accessories\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/prideshop.eu\/en\/product-category\/sports\/taekwondo-wt-olympic-sports\/taekwondo-wt-accessories\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prideshop.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Sports","item":"https:\/\/prideshop.eu\/en\/product-category\/sports\/"},{"@type":"ListItem","position":3,"name":"Taekwondo WT Olympic sports","item":"https:\/\/prideshop.eu\/en\/product-category\/sports\/taekwondo-wt-olympic-sports\/"},{"@type":"ListItem","position":4,"name":"Taekwondo WT Accessories"}]},{"@type":"WebSite","@id":"https:\/\/prideshop.eu\/en\/#website","url":"https:\/\/prideshop.eu\/en\/","name":"PRIDEshop","description":"Oprema za Borilne \u0160porte","publisher":{"@id":"https:\/\/prideshop.eu\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prideshop.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/prideshop.eu\/en\/#organization","name":"PRIDEshop","url":"https:\/\/prideshop.eu\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/prideshop.eu\/en\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"PRIDEshop"},"image":{"@id":"https:\/\/prideshop.eu\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/sl-si.facebook.com\/PrideShopeu"]}]}},"_links":{"self":[{"href":"https:\/\/prideshop.eu\/en\/wp-json\/wp\/v2\/product_cat\/1910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prideshop.eu\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/prideshop.eu\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/prideshop.eu\/en\/wp-json\/wp\/v2\/product_cat\/755"}],"wp:post_type":[{"href":"https:\/\/prideshop.eu\/en\/wp-json\/wp\/v2\/product?product_cat=1910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}